{"id":74343,"date":"2026-03-27T19:09:30","date_gmt":"2026-03-27T18:09:30","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=74343"},"modified":"2026-03-27T19:09:30","modified_gmt":"2026-03-27T18:09:30","slug":"womens-words-4","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/womens-words-4-74343\/","title":{"rendered":"Womens&#8216; Words"},"content":{"rendered":"<p>Schreiben kann therapeutisch sein. Es hilft, die Gedanken zu ordnen,\u00a0regt die Fantasie an und schafft Raum f\u00fcr Reflexion. Wie jede kreative T\u00e4tigkeit, braucht auch Schreiben Zeit und Mu\u00dfe,\u00a0damit die Vorstellungskraft wirklich zum Leben erwachen kann.<\/p>\n<p>Nimm an einem strukturierten, kreativen Schreibkurs teil \u2013 umgeben von Frauen, die lernen, schreiben und sich gegenseitig inspirieren. \u00a0In einer offenen, freundlichen Atmosph\u00e4re unterst\u00fctzt die Kursleiterin deine Ideen und den Schreibprozess. Bring einen Laptop, ein Notizbuch oder loses Papier mit\u00a0\u2013 was auch immer f\u00fcr dich am besten funktioniert.<\/p>\n<p>Die Anleitung und Diskussionen finden auf Englisch und Deutsch statt, die Teilnehmenden sind eingeladen, in der Sprache ihrer Wahl zu schreiben. Das Teilen eigener Texte ist erw\u00fcnscht, aber nicht erforderlich. Alle Erfahrungslevels sind willkommen.<\/p>\n<p><strong>\u00dcber Sonja Webster:<\/strong><br \/>\nSonja Webster ist englische und deutsche Muttersprachlerin und Autorin, die in Heidelberg lebt. Sie ist \u00fcberzeugt, dass jede Frau, die schreibt, eine Schriftstellerin ist \u2013 ohne eine besondere Ausbildung. Sonja liebte das Schreiben und Geschichtenerz\u00e4hlen schon immer, begann aber professionelles Schreiben erst, als ihre Kinder noch klein waren. Ihr Deb\u00fctroman <i>Royal Training<\/i>\u00a0erschien im April 2025.<\/p>\n<p><strong>Kontakt:<\/strong>\u00a0<a id=\"menur43k\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"&#x6d;&#97;&#x69;&#x6c;&#116;&#x6f;&#x3a;&#108;&#x69;&#x62;&#114;&#x61;&#x72;y&#x40;&#x64;a&#x69;&#45;h&#x65;&#105;d&#x65;&#108;b&#x65;&#114;g&#x2e;&#100;e\" href=\"&#109;&#97;&#x69;l&#116;&#x6f;&#x3a;l&#105;&#x62;&#x72;a&#114;&#x79;&#x40;d&#97;&#x69;&#x2d;h&#101;&#x69;&#x64;e&#108;&#x62;e&#114;&#103;&#x2e;d&#101;\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Link &#108;&#x69;&#98;&#x72;&#97;&#x72;&#121;&#x40;&#100;&#x61;&#105;&#x2d;&#104;&#x65;&#105;&#x64;&#101;&#x6c;&#98;&#x65;&#114;&#x67;&#46;&#x64;&#101;\">&#108;&#x69;&#x62;&#114;&#x61;&#x72;y&#x40;&#x64;a&#105;&#x2d;h&#101;&#x69;d&#101;&#x6c;b&#101;&#x72;g&#46;&#x64;&#x65;<\/a><br \/>\nBitte melden Sie sich im Voraus an.<\/p>\n<p><strong>Termine:\u00a0<\/strong>w\u00f6chentlich ab dem 17. April<strong>\u00a0<\/strong><br \/>\n<i>Jeden Freitag, 9:00 \u2013 10:30 Uhr<\/i><\/p>\n<p><strong>Sprache:<\/strong>\u00a0Englisch &amp; Deutsch<\/p>\n<p><strong>Geb\u00fchr:<\/strong>\u00a010 \u20ac pro Termin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schreiben kann therapeutisch sein. Es hilft, die Gedanken zu ordnen,\u00a0regt die Fantasie an und schafft Raum f\u00fcr Reflexion. Wie jede&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":74335,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[7],"dai_event_type":[19],"dai_event_location":[],"class_list":["post-74343","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-bibliothek","dai_event_type-social-activities"],"better_featured_image":{"id":74335,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2026\/03\/Womans-Words.jpg","filesize":81062,"sizes":{"medium":{"file":"Womans-Words-300x135.jpg","width":300,"height":135,"mime-type":"image\/jpeg","filesize":11030,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-300x135.jpg"},"thumbnail":{"file":"Womans-Words-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":11018,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-150x150.jpg"},"medium_large":{"file":"Womans-Words-768x347.jpg","width":768,"height":347,"mime-type":"image\/jpeg","filesize":40413,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-768x347.jpg"},"dai-list":{"file":"Womans-Words-140x140.jpg","width":140,"height":140,"mime-type":"image\/jpeg","filesize":10352,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-140x140.jpg"},"dai-selector":{"file":"Womans-Words-240x170.jpg","width":240,"height":170,"mime-type":"image\/jpeg","filesize":13386,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-240x170.jpg"},"dai-hof":{"file":"Womans-Words-240x192.jpg","width":240,"height":192,"mime-type":"image\/jpeg","filesize":15171,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words-240x192.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":73842,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg"},"post-meta-fields":{"_thumbnail_id":["74335"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_wordproof_timestamp":[""],"dai_event_datetime":["2026-05-15 09:00"],"dai_event_featured":["0"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"dai_event_status":["planned"],"dai_event_language":["en"],"dai_event_type":["at_location"],"dai_event_venus_id":["6967c560271a4e9826f91285"],"dai_event_venus_image_id":["69c69e9a13f332ecff199ec4"],"dai_event_venus_image_thumbnail_id":["74335"],"dai_event_venus_updated_at":["2026-05-04 12:13:21"],"dai_event_datetime_end":["2026-05-15 10:30"],"dai_event_artist":["Schreib-Workshop f\u00fcr Frauen mit Sonja Webster"],"_dp_original":["74340"],"_edit_lock":["1774634913:10"],"_edit_last":["10"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"Schreiben kann therapeutisch sein. Es hilft, die Gedanken zu ordnen,\u00a0regt die Fantasie an und schafft Raum f\u00fcr Reflexion. Wie jede&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=74343\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Womans-Words.jpg\",\"datePublished\":\"2026-03-27T18:09:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Womans-Words.jpg\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Womans-Words.jpg\",\"width\":820,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=74343#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Womens&#8216; Words\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"Schreiben kann therapeutisch sein. Es hilft, die Gedanken zu ordnen,\u00a0regt die Fantasie an und schafft Raum f\u00fcr Reflexion. Wie jede&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343","og_site_name":"DAI Deutsch","og_image":[{"width":820,"height":370,"url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg","type":"image\/jpeg"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg","datePublished":"2026-03-27T18:09:30+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Womans-Words.jpg","width":820,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=74343#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Womens&#8216; Words"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/74343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":2,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/74343\/revisions"}],"predecessor-version":[{"id":74345,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/74343\/revisions\/74345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/74335"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=74343"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=74343"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=74343"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=74343"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=74343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}