{"id":72092,"date":"2025-12-04T10:28:30","date_gmt":"2025-12-04T09:28:30","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=72092"},"modified":"2025-12-04T10:28:30","modified_gmt":"2025-12-04T09:28:30","slug":"dai-writing-center-23","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/dai-writing-center-23-72092\/","title":{"rendered":"DAI Writing Center"},"content":{"rendered":"<p>Welcome to our DAI Writing Center \u2013 a uniquely \u00adcreative and collaborative space for people of different ages, stages, and walks of life to write their stories, novels, poems, movie scripts etc. while benefiting from feedback and companionship from other writers.<br \/>\nThe DAI Writing Center offers classes and workshops (in collaboration with our DAI Language School) on different literary genres \u2013 to give aspiring writers the tools and confidence to get started. We also host reading series, invite accomplished writers to share feedback to those getting started, organize focused writing sessions, and encourage participants to join our annual writing contests including the DAI Novel Prize for debut work.<\/p>\n<p><strong>For the overall theme and the dates, please contact:<\/strong> <a href=\"&#109;&#x61;&#x69;l&#116;&#x6f;&#x3a;l&#105;&#x62;r&#97;&#x72;&#x79;&#64;&#100;&#x61;i&#45;&#x68;&#x65;i&#100;&#x65;&#x6c;&#98;&#x65;&#x72;g&#46;&#x64;&#x65;\">&#108;&#x69;&#98;&#x72;a&#x72;y&#64;&#x64;&#97;&#x69;&#45;&#x68;e&#x69;d&#101;&#x6c;&#98;&#x65;r&#x67;&#46;&#x64;&#x65;<\/a><br \/>\nPlease register ahead of time.<\/p>\n<p><strong>Age:<\/strong> 18+ years<\/p>\n<p><strong>Dates:<\/strong><br \/>\nJanuary 17 &amp; 31<br \/>\nFebruary 28<\/p>\n<p><em>One or two Saturdays a month, 11:00 a.m.\u200a\u2013\u200a12:30 p.m.<\/em><\/p>\n<p><strong>Language:<\/strong> English<\/p>\n<p><strong>Course fee:<\/strong> 10 \u20ac per session<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welcome to our DAI Writing Center \u2013 a uniquely \u00adcreative and collaborative space for people of different ages, stages, and&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":60902,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[7],"dai_event_type":[229,19],"dai_event_location":[],"class_list":["post-72092","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-bibliothek","dai_event_type-literarisches-zentrum-heidelberg","dai_event_type-social-activities"],"better_featured_image":{"id":60902,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2024\/01\/Homepage-Veranstaltung8.png","filesize":523977,"sizes":{"medium":{"file":"Homepage-Veranstaltung8-300x135.png","width":300,"height":135,"mime-type":"image\/png","filesize":71128,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-300x135.png"},"thumbnail":{"file":"Homepage-Veranstaltung8-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":42403,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-150x150.png"},"medium_large":{"file":"Homepage-Veranstaltung8-768x347.png","width":768,"height":347,"mime-type":"image\/png","filesize":414885,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-768x347.png"},"dai-list":{"file":"Homepage-Veranstaltung8-140x140.png","width":140,"height":140,"mime-type":"image\/png","filesize":37362,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-140x140.png"},"dai-selector":{"file":"Homepage-Veranstaltung8-240x170.png","width":240,"height":170,"mime-type":"image\/png","filesize":76636,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-240x170.png"},"dai-hof":{"file":"Homepage-Veranstaltung8-240x192.png","width":240,"height":192,"mime-type":"image\/png","filesize":85308,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8-240x192.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":60901,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png"},"post-meta-fields":{"_thumbnail_id":["60902"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_wordproof_timestamp":[""],"dai_event_datetime":["2026-01-31 11:00"],"dai_event_featured":["0"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"dai_event_status":["planned"],"dai_event_language":["en"],"dai_event_type":["at_location"],"_dp_original":["72089"],"_edit_lock":["1764840387:20"],"_edit_last":["20"],"dai_event_venus_id":["6967c475271a4e9826f8e365"],"dai_event_venus_image_id":["6967c477089d7e29d11f941f"],"dai_event_venus_image_thumbnail_id":["60902"],"dai_event_venus_updated_at":["2026-01-14 16:29:44"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"Welcome to our DAI Writing Center \u2013 a uniquely \u00adcreative and collaborative space for people of different ages, stages, and&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=72092\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/Homepage-Veranstaltung8.png\",\"datePublished\":\"2025-12-04T09:28:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/Homepage-Veranstaltung8.png\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/Homepage-Veranstaltung8.png\",\"width\":820,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=72092#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DAI Writing Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"Welcome to our DAI Writing Center \u2013 a uniquely \u00adcreative and collaborative space for people of different ages, stages, and&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092","og_site_name":"DAI Deutsch","og_image":[{"width":820,"height":370,"url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png","type":"image\/png"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png","datePublished":"2025-12-04T09:28:30+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/Homepage-Veranstaltung8.png","width":820,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=72092#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"DAI Writing Center"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/72092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":2,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/72092\/revisions"}],"predecessor-version":[{"id":72094,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/72092\/revisions\/72094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/60902"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=72092"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=72092"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=72092"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=72092"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=72092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}