{"id":70550,"date":"2025-08-04T15:36:51","date_gmt":"2025-08-04T13:36:51","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=70550"},"modified":"2025-12-19T15:10:30","modified_gmt":"2025-12-19T14:10:30","slug":"naehcafe-114","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/naehcafe-114-70550\/","title":{"rendered":"N\u00e4hcaf\u00e9"},"content":{"rendered":"<p>Im N\u00e4hcaf\u00e9 k\u00f6nnen Sie kreativ Deutsch lernen. Egal, ob Sie sich mit anderen austauschen m\u00f6chten, die Ihre Leidenschaft f\u00fcrs N\u00e4hen teilen, oder ob Sie mit den Grundlagen starten, in unserem N\u00e4hcaf\u00e9 sind alle willkommen. W\u00e4hrend Sie unter Anleitung Ihre Kleidung reparieren oder neue St\u00fccke entwerfen, kommen Sie von allein mit der deutschen Sprache in Kontakt. Bringen Sie Ihr eigenes Projekt mit oder verwenden Sie unsere \u00adMaterialien zum \u00dcben. N\u00e4hmaschinen sind vorhanden.<\/p>\n<p><em>Dienstags 15:00 \u2013 18:00 Uhr<\/em><\/p>\n<p><strong>Sprachen:<\/strong> international<\/p>\n<p><strong>Anmeldung:<\/strong> <a href=\"&#x6d;&#97;&#x69;&#x6c;t&#x6f;&#58;l&#x69;&#98;r&#x61;&#114;&#x79;&#x40;d&#x61;&#105;-&#x68;&#101;i&#x64;&#101;&#x6c;&#x62;&#101;&#x72;&#x67;&#46;&#x64;&#101;\">&#108;&#x69;&#x62;r&#97;&#x72;&#x79;&#64;&#100;&#x61;i&#45;&#x68;&#x65;i&#100;&#x65;l&#98;&#x65;&#x72;g&#46;&#x64;&#x65;<\/a><br \/>\n(Bitte kontaktieren Sie uns auf Deutsch oder Englisch)<\/p>\n<p>Der <strong>Eintritt ist frei<\/strong>. Wenn Sie regelm\u00e4\u00dfig teilnehmen m\u00f6chten, werden Sie bitte Mitglied der DAI-Bibliothek.<\/p>\n<hr \/>\n<p>\u0423 \u0448\u0432\u0435\u0439\u043d\u0456\u0439 \u043a\u0430\u0432\u2019\u044f\u0440\u043d\u0456 \u0432\u0438 \u043c\u043e\u0436\u0435\u0442\u0435 \u0432\u0438\u0432\u0447\u0430\u0442\u0438 \u043d\u0456\u043c\u0435\u0446\u044c\u043a\u0443 \u043c\u043e\u0432\u0443 \u0442\u0432\u043e\u0440\u0447\u043e. \u041d\u0435\u0437\u0430\u043b\u0435\u0436\u043d\u043e \u0432\u0456\u0434 \u0442\u043e\u0433\u043e, \u0447\u0438 \u0445\u043e\u0447\u0435\u0442\u0435 \u0432\u0438 \u043e\u0431\u043c\u0456\u043d\u044f\u0442\u0438\u0441\u044f \u0456\u0434\u0435\u044f\u043c\u0438 \u0437 \u0442\u0438\u043c\u0438, \u0445\u0442\u043e \u043f\u043e\u0434\u0456\u043b\u044f\u0454 \u0432\u0430\u0448\u0443 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u044c \u0434\u043e \u0448\u0438\u0442\u0442\u044f, \u0447\u0438 \u043f\u043e\u0447\u0430\u0442\u0438 \u0437 \u0430\u0437\u0456\u0432, \u0443 \u043d\u0430\u0448\u043e\u043c\u0443 \u0448\u0432\u0435\u0439\u043d\u043e\u043c\u0443 \u043a\u0430\u0444\u0435 \u0440\u0430\u0434\u0456 \u043a\u043e\u0436\u043d\u043e\u043c\u0443. \u0420\u0435\u043c\u043e\u043d\u0442\u0443\u044e\u0447\u0438 \u0441\u0432\u0456\u0439 \u043e\u0434\u044f\u0433 \u0430\u0431\u043e \u0441\u0442\u0432\u043e\u0440\u044e\u044e\u0447\u0438 \u043d\u043e\u0432\u0456 \u0440\u0435\u0447\u0456 \u043f\u0456\u0434 \u043a\u0435\u0440\u0456\u0432\u043d\u0438\u0446\u0442\u0432\u043e\u043c, \u0432\u0438 \u0430\u0432\u0442\u043e\u043c\u0430\u0442\u0438\u0447\u043d\u043e \u043a\u043e\u043d\u0442\u0430\u043a\u0442\u0443\u0454\u0442\u0435 \u0437 \u043d\u0456\u043c\u0435\u0446\u044c\u043a\u043e\u044e \u043c\u043e\u0432\u043e\u044e. \u041f\u0440\u0438\u043d\u043e\u0441\u044c\u0442\u0435 \u0441\u0432\u0456\u0439 \u0432\u043b\u0430\u0441\u043d\u0438\u0439 \u043f\u0440\u043e\u0435\u043a\u0442 \u0430\u0431\u043e \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0439\u0442\u0435 \u043d\u0430\u0448\u0456 \u043c\u0430\u0442\u0435\u0440\u0456\u0430\u043b\u0438 \u0434\u043b\u044f \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0438. \u0428\u0432\u0435\u0439\u043d\u0456 \u043c\u0430\u0448\u0438\u043d\u043a\u0438 \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u0456.<\/p>\n<p><strong>\u0412\u0445\u0456\u0434 \u0432\u0456\u043b\u044c\u043d\u0438\u0439. \u0420\u0435\u0454\u0441\u0442\u0440\u0430\u0446\u0456\u044f:<\/strong> <a href=\"&#x6d;&#97;&#x69;&#x6c;&#116;&#x6f;&#x3a;&#108;&#x69;&#x62;&#114;&#x61;&#x72;y&#x40;&#x64;a&#x69;&#45;h&#x65;&#105;d&#x65;&#108;b&#x65;&#114;g&#x2e;&#100;e\">&#x6c;&#105;b&#x72;&#x61;&#114;y&#x40;&#x64;&#97;i&#x2d;&#104;e&#x69;&#x64;&#101;l&#x62;&#x65;&#114;g&#x2e;&#100;&#101;<\/a><br \/>\n(\u0411\u0443\u0434\u044c \u043b\u0430\u0441\u043a\u0430, \u0437\u0432\u0435\u0440\u0442\u0430\u0439\u0442\u0435\u0441\u044f \u0434\u043e \u043d\u0430\u0441 \u043d\u0456\u043c\u0435\u0446\u044c\u043a\u043e\u044e \u0430\u0431\u043e \u0430\u043d\u0433\u043b\u0456\u0439\u0441\u044c\u043a\u043e\u044e \u043c\u043e\u0432\u043e\u044e)<\/p>\n<p><em>\u0412\u0456\u0432\u0442\u043e\u0440\u043e\u043a 15:00 \u2013 18:00<\/em><\/p>\n<p>\u041c\u043e\u0432\u0438: \u043c\u0456\u0436\u043d\u0430\u0440\u043e\u0434\u043d\u0456<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im N\u00e4hcaf\u00e9 k\u00f6nnen Sie kreativ Deutsch lernen. Egal, ob Sie sich mit anderen austauschen m\u00f6chten, die Ihre Leidenschaft f\u00fcrs N\u00e4hen&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":56191,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[7],"dai_event_type":[19],"dai_event_location":[],"class_list":["post-70550","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-bibliothek","dai_event_type-social-activities"],"better_featured_image":{"id":56191,"alt_text":"Nadelkissen, Nadeln, Scheere","caption":"","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2023\/05\/Naehcafe.png","filesize":401712,"sizes":{"medium":{"file":"Naehcafe-300x135.png","width":300,"height":135,"mime-type":"image\/png","filesize":63892,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-300x135.png"},"thumbnail":{"file":"Naehcafe-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":37457,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-150x150.png"},"medium_large":{"file":"Naehcafe-768x347.png","width":768,"height":347,"mime-type":"image\/png","filesize":332500,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-768x347.png"},"dai-list":{"file":"Naehcafe-140x140.png","width":140,"height":140,"mime-type":"image\/png","filesize":33071,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-140x140.png"},"dai-selector":{"file":"Naehcafe-240x170.png","width":240,"height":170,"mime-type":"image\/png","filesize":64522,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-240x170.png"},"dai-hof":{"file":"Naehcafe-240x192.png","width":240,"height":192,"mime-type":"image\/png","filesize":71216,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe-240x192.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":56051,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png"},"post-meta-fields":{"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"_yoast_wpseo_wordproof_timestamp":[""],"dai_event_datetime":["2025-12-23 15:00"],"dai_event_featured":["0"],"dai_event_ticket_freeadmission":["1"],"dai_autotranslate_should_translate":["1"],"_thumbnail_id":["56191"],"_dp_original":["70547"],"_edit_lock":["1766153825:10"],"_edit_last":["10"],"dai_event_status":["cancelled"],"dai_event_language":["en"],"dai_event_type":["at_location"],"dai_event_notice":["Entf\u00e4llt"],"dai_event_content_notice":["Entf\u00e4llt"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"Im N\u00e4hcaf\u00e9 k\u00f6nnen Sie kreativ Deutsch lernen. Egal, ob Sie sich mit anderen austauschen m\u00f6chten, die Ihre Leidenschaft f\u00fcrs N\u00e4hen&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=70550\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T14:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/05\\\/Naehcafe.png\",\"datePublished\":\"2025-08-04T13:36:51+00:00\",\"dateModified\":\"2025-12-19T14:10:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/05\\\/Naehcafe.png\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/05\\\/Naehcafe.png\",\"width\":820,\"height\":370,\"caption\":\"Nadelkissen, Nadeln, Scheere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70550#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00e4hcaf\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"Im N\u00e4hcaf\u00e9 k\u00f6nnen Sie kreativ Deutsch lernen. Egal, ob Sie sich mit anderen austauschen m\u00f6chten, die Ihre Leidenschaft f\u00fcrs N\u00e4hen&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550","og_site_name":"DAI Deutsch","article_modified_time":"2025-12-19T14:10:30+00:00","og_image":[{"width":820,"height":370,"url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png","type":"image\/png"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png","datePublished":"2025-08-04T13:36:51+00:00","dateModified":"2025-12-19T14:10:30+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/05\/Naehcafe.png","width":820,"height":370,"caption":"Nadelkissen, Nadeln, Scheere"},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70550#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"N\u00e4hcaf\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":2,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70550\/revisions"}],"predecessor-version":[{"id":72554,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70550\/revisions\/72554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/56191"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=70550"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=70550"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=70550"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=70550"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=70550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}