{"id":70145,"date":"2025-08-01T11:44:54","date_gmt":"2025-08-01T09:44:54","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=70145"},"modified":"2025-08-01T11:44:54","modified_gmt":"2025-08-01T09:44:54","slug":"mini-drama-queens-kings-64","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/mini-drama-queens-kings-64-70145\/","title":{"rendered":"Mini Drama Queens &amp; Kings"},"content":{"rendered":"<p>The DAI Library offers a drama group for children ages 5 to 7. Working with our instructor, Janet Grau (Raum der K\u00fcnste Heidelberg), we learn what \u201cdrama\u201d really means. We play, we pretend, we sing and dance and draw. We look forward to presenting our dramatic ideas on stage! Participants should be native English speakers or children with a reasonable level of English.<\/p>\n<p><strong>Contact<\/strong>: <a href=\"m&#97;&#x69;&#x6c;t&#111;&#58;&#x6c;&#x69;b&#114;&#97;&#x72;&#x79;&#64;&#100;&#x61;&#x69;&#x2d;h&#101;&#x69;&#x64;e&#108;&#98;&#x65;&#x72;g&#46;&#100;&#x65;\">l&#105;&#x62;&#x72;a&#114;&#121;&#x40;&#x64;a&#105;&#x2d;&#x68;e&#105;&#100;&#x65;&#x6c;b&#101;&#x72;&#x67;&#46;&#100;&#101;<\/a><\/p>\n<p>This program has a limited number of participants. Please register your child ahead of time (one trial session \u00adpossible).<\/p>\n<p>Please note: This program is designed as a continuous \u00adexperience running from September through July. Although payment is processed quarterly for administrative purposes, we highly \u00adrecommend participating for the full duration.<\/p>\n<p><strong>Dates<\/strong>: weekly from September 25 onwards (12 meetings until Christmas)<br \/>\n<em>Every Thursday, 4:30\u200a\u2013\u200a5:30 p.m. (excluding school and public holidays)<\/em><\/p>\n<p><strong>Language<\/strong>: English<\/p>\n<p>Course fee (per quarter): 175 \u20ac (10 % discount for DAI members)<br \/>\nPlease collect the current quarter\u2019s registration form at the library desk and submit it in person or via e-mail by October 02. Payment is then made by authorized direct debit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The DAI Library offers a drama group for children ages 5 to 7. Working with our instructor, Janet Grau (Raum&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":70142,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[7,8],"dai_event_type":[14,19],"dai_event_location":[],"class_list":["post-70145","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-bibliothek","dai_event_category-u20","dai_event_type-kinderprogramm","dai_event_type-social-activities"],"better_featured_image":{"id":70142,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2025\/08\/Mini-Drama-Queens-Kings.jpg","filesize":19870,"sizes":{"medium":{"file":"Mini-Drama-Queens-Kings-300x135.jpg","width":300,"height":135,"mime-type":"image\/jpeg","filesize":8171,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-300x135.jpg"},"thumbnail":{"file":"Mini-Drama-Queens-Kings-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7334,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-150x150.jpg"},"medium_large":{"file":"Mini-Drama-Queens-Kings-768x347.jpg","width":768,"height":347,"mime-type":"image\/jpeg","filesize":16745,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-768x347.jpg"},"dai-list":{"file":"Mini-Drama-Queens-Kings-140x140.jpg","width":140,"height":140,"mime-type":"image\/jpeg","filesize":7068,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-140x140.jpg"},"dai-selector":{"file":"Mini-Drama-Queens-Kings-240x170.jpg","width":240,"height":170,"mime-type":"image\/jpeg","filesize":9089,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-240x170.jpg"},"dai-hof":{"file":"Mini-Drama-Queens-Kings-240x192.jpg","width":240,"height":192,"mime-type":"image\/jpeg","filesize":9461,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings-240x192.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":70140,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg"},"post-meta-fields":{"_thumbnail_id":["70142"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_wordproof_timestamp":[""],"dai_event_datetime":["2025-10-02 16:30"],"dai_event_featured":["0"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"_dp_original":["70140"],"_edit_lock":["1754041369:20"],"_edit_last":["20"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"The DAI Library offers a drama group for children ages 5 to 7. Working with our instructor, Janet Grau (Raum&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=70145\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/08\\\/Mini-Drama-Queens-Kings.jpg\",\"datePublished\":\"2025-08-01T09:44:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/08\\\/Mini-Drama-Queens-Kings.jpg\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/08\\\/Mini-Drama-Queens-Kings.jpg\",\"width\":820,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=70145#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mini Drama Queens &amp; Kings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"The DAI Library offers a drama group for children ages 5 to 7. Working with our instructor, Janet Grau (Raum&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145","og_site_name":"DAI Deutsch","og_image":[{"width":820,"height":370,"url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg","type":"image\/jpeg"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg","datePublished":"2025-08-01T09:44:54+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2025\/08\/Mini-Drama-Queens-Kings.jpg","width":820,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=70145#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Mini Drama Queens &amp; Kings"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":2,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70145\/revisions"}],"predecessor-version":[{"id":70147,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/70145\/revisions\/70147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/70142"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=70145"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=70145"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=70145"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=70145"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=70145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}