{"id":69768,"date":"2025-07-30T16:31:47","date_gmt":"2025-07-30T14:31:47","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=69768"},"modified":"2026-03-25T19:09:00","modified_gmt":"2026-03-25T18:09:00","slug":"zoe-schlanger","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/zoe-schlanger-69768\/","title":{"rendered":"Zo\u00eb Schlanger"},"content":{"rendered":"<p>Pflanzen \u00fcberqueren Ozeane, verwandeln Licht in Leben und nehmen wahr, was uns verborgen bleibt. Sie f\u00fchren komplexe Sozialleben und helfen dabei, die scheinbar unvermeidliche Klimakatastrophe aufzuhalten. Dass unser Planet bewohnbar ist, verdanken wir diesen Gesch\u00f6pfen, die uns zugleich vertraut und fremd sind. Voller Neugier sp\u00fcrt Zo\u00eb Schlanger den Geheimnissen der Pflanzenwelt und der Verbundenheit alles Lebendigen nach. Sie erz\u00e4hlt von der Anpassungsf\u00e4higkeit und den ausgekl\u00fcgelten \u00dcberlebenstechniken der Pflanzen, denen es gelingt, die ungeeignetsten Orte zu ihrem Lebensraum zu machen. Dabei taucht sie in die faszinierende Welt der Botanik ein und verwebt ihre Erkenntnisse mit philosophischen \u00dcberlegungen \u00fcber die Zusammenh\u00e4nge des Lebens.<\/p>\n<p><strong>Zo\u00eb Schlanger<\/strong> ist eine vielfach ausgezeichnete Wissenschaftsjournalistin. Ihre Artikel erscheinen in der New York Times und dem TIME Magazin. Schlanger lebt in Montreal und New York.<\/p>\n<p><strong>Sprache:<\/strong> Englisch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pflanzen \u00fcberqueren Ozeane, verwandeln Licht in Leben und nehmen wahr, was uns verborgen bleibt. Sie f\u00fchren komplexe Sozialleben und helfen&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[6],"dai_event_type":[209,21],"dai_event_location":[],"class_list":["post-69768","dai_event","type-dai_event","status-publish","hentry","dai_event_category-kulturveranstaltungen","dai_event_type-geist-heidelberg","dai_event_type-vortrag"],"better_featured_image":null,"post-meta-fields":{"_edit_lock":["1774462023:10"],"_edit_last":["10"],"dai_event_datetime":["2025-10-19 17:00"],"dai_event_featured":["0"],"dai_event_artist":["Die Lichtwandler"],"dai_event_subtext":["Wie Pflanzen uns das Leben schenken"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"dai_event_ticket_link":["https:\/\/shop.reservix.de\/?id=36ae96de8dddc4df70dce3f39db2b886ff117b9261533f02fa35ea4a3191d65e3a64633f4652f2d1ba3a365eff82ca70&vID=2736&eventGrpID=513224&eventID=2444922"],"dai_event_ticket_price_presale_standard":["11,90"],"dai_event_ticket_price_presale_reduced":["9,90"],"dai_event_ticket_price_presale_member":["6,90"],"dai_event_status":["planned"],"dai_event_language":["en"],"dai_event_type":["at_location"],"dai_event_venus_id":["69c424bece24914090c6ae65"],"dai_event_venus_updated_at":["2026-03-25 18:09:02"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"Pflanzen \u00fcberqueren Ozeane, verwandeln Licht in Leben und nehmen wahr, was uns verborgen bleibt. Sie f\u00fchren komplexe Sozialleben und helfen&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=69768\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T18:09:00+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=69768\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=69768\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"datePublished\":\"2025-07-30T14:31:47+00:00\",\"dateModified\":\"2026-03-25T18:09:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=69768#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=69768\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=69768#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zo\u00eb Schlanger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"Pflanzen \u00fcberqueren Ozeane, verwandeln Licht in Leben und nehmen wahr, was uns verborgen bleibt. Sie f\u00fchren komplexe Sozialleben und helfen&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768","og_site_name":"DAI Deutsch","article_modified_time":"2026-03-25T18:09:00+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"datePublished":"2025-07-30T14:31:47+00:00","dateModified":"2026-03-25T18:09:00+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=69768#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Zo\u00eb Schlanger"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/69768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":1,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/69768\/revisions"}],"predecessor-version":[{"id":69773,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/69768\/revisions\/69773"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=69768"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=69768"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=69768"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=69768"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=69768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}