{"id":64028,"date":"2024-07-16T13:58:33","date_gmt":"2024-07-16T11:58:33","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=64028"},"modified":"2024-07-16T13:58:33","modified_gmt":"2024-07-16T11:58:33","slug":"story-time-for-school-children-20","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/story-time-for-school-children-20-64028\/","title":{"rendered":"Story Time for School Children"},"content":{"rendered":"<p>There are so many great picture books for older children that we decided to offer an entire Story Time for children ages 7 to 10. This will be a time for kids to kick back, relax, and listen to a story or two.<\/p>\n<p>This Story Time is followed by a Library Hangout \u2013 where you can swing by and get to know the other kids and their families that use the library on a regular basis. Additionally, our Book Fairy Lynne will give you book recommendations &#8211; thoughtfully handpicked good reads tailored to your individual interests.<\/p>\n<p><strong>Contact:<\/strong> <a href=\"&#x6d;&#x61;&#x69;&#x6c;&#116;&#111;&#58;&#108;ibr&#x61;&#x72;&#x79;&#x40;&#x64;&#97;&#105;&#45;hei&#x64;&#x65;&#x6c;&#x62;&#x65;&#114;&#103;&#46;de\">&#108;&#x69;&#98;&#x72;&#97;&#x72;&#121;&#x40;&#100;&#x61;&#105;&#x2d;&#104;&#x65;&#105;&#x64;&#101;&#x6c;&#98;&#x65;&#114;&#x67;&#46;&#x64;&#101;<\/a><br \/>\nPlease register your child ahead of time.<\/p>\n<p><em>Every Friday, 4:00\u200a\u2013\u200a5:00 p.m. <\/em><\/p>\n<p><strong>Language:<\/strong> English<\/p>\n<p>The program is free of charge, but donations to cover the cost of craft supplies are greatly appreciated. If your child would like to participate on a regular basis, please become a member of the DAI Library.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>There are so many great picture books for older children that we decided to offer an entire Story Time for&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":60618,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[7,8],"dai_event_type":[14,229,19,232],"dai_event_location":[],"class_list":["post-64028","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-bibliothek","dai_event_category-u20","dai_event_type-kinderprogramm","dai_event_type-literarisches-zentrum-heidelberg","dai_event_type-social-activities","dai_event_type-story-time-for-kids"],"better_featured_image":{"id":60618,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2023\/12\/Story-Time-for-Older-Children.jpg","filesize":104221,"sizes":{"medium":{"file":"Story-Time-for-Older-Children-300x135.jpg","width":300,"height":135,"mime-type":"image\/jpeg","filesize":13696,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-300x135.jpg"},"thumbnail":{"file":"Story-Time-for-Older-Children-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8402,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-150x150.jpg"},"medium_large":{"file":"Story-Time-for-Older-Children-768x347.jpg","width":768,"height":347,"mime-type":"image\/jpeg","filesize":56507,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-768x347.jpg"},"dai-list":{"file":"Story-Time-for-Older-Children-140x140.jpg","width":140,"height":140,"mime-type":"image\/jpeg","filesize":7452,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-140x140.jpg"},"dai-selector":{"file":"Story-Time-for-Older-Children-240x170.jpg","width":240,"height":170,"mime-type":"image\/jpeg","filesize":13367,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-240x170.jpg"},"dai-hof":{"file":"Story-Time-for-Older-Children-240x192.jpg","width":240,"height":192,"mime-type":"image\/jpeg","filesize":14576,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children-240x192.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":60617,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg"},"post-meta-fields":{"_thumbnail_id":["60618"],"dai_event_datetime":["2024-10-11 16:00"],"dai_event_featured":["0"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"_dp_original":["64025"],"_edit_lock":["1721130990:20"],"_edit_last":["20"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"There are so many great picture books for older children that we decided to offer an entire Story Time for&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=64028\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/12\\\/Story-Time-for-Older-Children.jpg\",\"datePublished\":\"2024-07-16T11:58:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/12\\\/Story-Time-for-Older-Children.jpg\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/12\\\/Story-Time-for-Older-Children.jpg\",\"width\":820,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=64028#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Story Time for School Children\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"There are so many great picture books for older children that we decided to offer an entire Story Time for&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028","og_site_name":"DAI Deutsch","og_image":[{"width":820,"height":370,"url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg","type":"image\/jpeg"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg","datePublished":"2024-07-16T11:58:33+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2023\/12\/Story-Time-for-Older-Children.jpg","width":820,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=64028#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Story Time for School Children"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/64028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":2,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/64028\/revisions"}],"predecessor-version":[{"id":64030,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/64028\/revisions\/64030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/60618"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=64028"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=64028"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=64028"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=64028"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=64028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}