{"id":61664,"date":"2024-03-11T14:12:53","date_gmt":"2024-03-11T13:12:53","guid":{"rendered":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&#038;p=61664"},"modified":"2024-09-04T20:28:49","modified_gmt":"2024-09-04T18:28:49","slug":"juergen-theobaldy-martin-grzimek","status":"publish","type":"dai_event","link":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/juergen-theobaldy-martin-grzimek-61664\/","title":{"rendered":"J\u00fcrgen Theobaldy &#038; Martin Grzimek"},"content":{"rendered":"<p>J\u00fcrgen Theobaldy ist ein genauer Beobachter. Seine Gedichte verbinden die politischen Erfahrungen seiner Generation mit dem unakademischen Gestus pers\u00f6nlicher Erfahrungen in einer gesellschaftlich bewegten, mehr und mehr popkulturellen Umgebung. Sinnlich und konkret, der Umgangssprache nahe, vergegenw\u00e4rtigen sie eine Jugend im proletarischen Mannheim, Sonntage auf Fu\u00dfballpl\u00e4tzen, die Liebe in Zeiten von Demonstrationen gegen atomare Hochr\u00fcstung, von Streiks und Berufsverboten.<\/p>\n<p>Mit einer eigenen poetischen Selbstbesinnung gilt Theobaldy heute als wichtiger Repr\u00e4sentant der sogenannten Neuen Subjektivit\u00e4t. Ihren Ansatz erweitert er in den Jahrzehnten danach um die Auseinandersetzung mit klassischer Lyrik von Sappho und Goethe bis Heym und Trakl. Seine Gedichte greifen weit aus in die Welt und die Gesellschaft \u2013 ein lyrisches Ereignis von allt\u00e4glicher Dringlichkeit!<\/p>\n<p>Der Schriftsteller <strong>Martin Grzimek<\/strong> spricht mit <strong>J\u00fcrgen Theobaldy<\/strong> \u00fcber dessen neuen Gedichtband und ehrt ihn damit zugleich zu seinem 80. Geburtstag.<\/p>\n<p>In Kooperation mit der UNESCO City of Literature<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00fcrgen Theobaldy ist ein genauer Beobachter. Seine Gedichte verbinden die politischen Erfahrungen seiner Generation mit dem unakademischen Gestus pers\u00f6nlicher Erfahrungen&nbsp;&hellip;<\/p>\n","protected":false},"featured_media":64923,"template":"","meta":{"footnotes":""},"tags":[],"dai_event_category":[6],"dai_event_type":[229,17],"dai_event_location":[],"class_list":["post-61664","dai_event","type-dai_event","status-publish","has-post-thumbnail","hentry","dai_event_category-kulturveranstaltungen","dai_event_type-literarisches-zentrum-heidelberg","dai_event_type-literatur"],"better_featured_image":{"id":64923,"alt_text":"","caption":"Foto: Tobas Dittmer","description":"","media_type":"image","media_details":{"width":820,"height":370,"file":"2024\/03\/240605_Theobaldy_Tobas-Dittmer.jpg","filesize":111177,"sizes":{"medium":{"file":"240605_Theobaldy_Tobas-Dittmer-300x135.jpg","width":300,"height":135,"mime-type":"image\/jpeg","filesize":11149,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-300x135.jpg"},"thumbnail":{"file":"240605_Theobaldy_Tobas-Dittmer-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5368,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-150x150.jpg"},"medium_large":{"file":"240605_Theobaldy_Tobas-Dittmer-768x347.jpg","width":768,"height":347,"mime-type":"image\/jpeg","filesize":50935,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-768x347.jpg"},"dai-list":{"file":"240605_Theobaldy_Tobas-Dittmer-140x140.jpg","width":140,"height":140,"mime-type":"image\/jpeg","filesize":5011,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-140x140.jpg"},"dai-selector":{"file":"240605_Theobaldy_Tobas-Dittmer-240x170.jpg","width":240,"height":170,"mime-type":"image\/jpeg","filesize":9805,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-240x170.jpg"},"dai-hof":{"file":"240605_Theobaldy_Tobas-Dittmer-240x192.jpg","width":240,"height":192,"mime-type":"image\/jpeg","filesize":9920,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer-240x192.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":61664,"source_url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer.jpg"},"post-meta-fields":{"_edit_lock":["1725474403:10"],"_edit_last":["10"],"dai_event_datetime":["2024-06-05 20:00"],"dai_event_featured":["0"],"dai_event_artist":["Nun wird es hell und du gehst raus"],"dai_event_subtext":["Ausgew\u00e4hlte Gedichte"],"dai_event_ticket_freeadmission":["0"],"dai_autotranslate_should_translate":["1"],"dai_event_ticket_link":["https:\/\/shop.reservix.de\/?id=36ae96de8dddc4df70dce3f39db2b886ff117b9261533f02fa35ea4a3191d65e3a64633f4652f2d1ba3a365eff82ca70&vID=2736&eventGrpID=464604&eventID=2244069"],"dai_event_ticket_price_presale_standard":["9,90"],"dai_event_ticket_price_presale_reduced":["6,90"],"dai_event_ticket_price_presale_member":["4,90"],"_thumbnail_id":["64923"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\" \/>\n<meta property=\"og:description\" content=\"J\u00fcrgen Theobaldy ist ein genauer Beobachter. Seine Gedichte verbinden die politischen Erfahrungen seiner Generation mit dem unakademischen Gestus pers\u00f6nlicher Erfahrungen&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&amp;p=61664\" \/>\n<meta property=\"og:site_name\" content=\"DAI Deutsch\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T18:28:49+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664\",\"name\":\"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/240605_Theobaldy_Tobas-Dittmer.jpg\",\"datePublished\":\"2024-03-11T13:12:53+00:00\",\"dateModified\":\"2024-09-04T18:28:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664#primaryimage\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/240605_Theobaldy_Tobas-Dittmer.jpg\",\"contentUrl\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/240605_Theobaldy_Tobas-Dittmer.jpg\",\"width\":820,\"height\":370,\"caption\":\"Foto: Tobas Dittmer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?post_type=dai_event&p=61664#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J\u00fcrgen Theobaldy &#038; Martin Grzimek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/\",\"name\":\"DAI Deutsch\",\"description\":\"Deutsch-Amerikanisches Institut. Haus der Kultur.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dai-heidelberg.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","og_description":"J\u00fcrgen Theobaldy ist ein genauer Beobachter. Seine Gedichte verbinden die politischen Erfahrungen seiner Generation mit dem unakademischen Gestus pers\u00f6nlicher Erfahrungen&nbsp;&hellip;","og_url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664","og_site_name":"DAI Deutsch","article_modified_time":"2024-09-04T18:28:49+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664","url":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664","name":"Veranstaltungen - Deutsch-Amerikanisches Institut. Haus der Kultur.","isPartOf":{"@id":"https:\/\/dai-heidelberg.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664#primaryimage"},"image":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664#primaryimage"},"thumbnailUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer.jpg","datePublished":"2024-03-11T13:12:53+00:00","dateModified":"2024-09-04T18:28:49+00:00","breadcrumb":{"@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664#primaryimage","url":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer.jpg","contentUrl":"https:\/\/dai-heidelberg.de\/de\/wp-content\/uploads\/sites\/2\/2024\/03\/240605_Theobaldy_Tobas-Dittmer.jpg","width":820,"height":370,"caption":"Foto: Tobas Dittmer"},{"@type":"BreadcrumbList","@id":"https:\/\/dai-heidelberg.de\/de\/?post_type=dai_event&p=61664#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dai-heidelberg.de\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/dai-heidelberg.de\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"J\u00fcrgen Theobaldy &#038; Martin Grzimek"}]},{"@type":"WebSite","@id":"https:\/\/dai-heidelberg.de\/de\/#website","url":"https:\/\/dai-heidelberg.de\/de\/","name":"DAI Deutsch","description":"Deutsch-Amerikanisches Institut. Haus der Kultur.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dai-heidelberg.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/61664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event"}],"about":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/types\/dai_event"}],"version-history":[{"count":1,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/61664\/revisions"}],"predecessor-version":[{"id":61665,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event\/61664\/revisions\/61665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media\/64923"}],"wp:attachment":[{"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/media?parent=61664"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/tags?post=61664"},{"taxonomy":"dai_event_category","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_category?post=61664"},{"taxonomy":"dai_event_type","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_type?post=61664"},{"taxonomy":"dai_event_location","embeddable":true,"href":"https:\/\/dai-heidelberg.de\/de\/wp-json\/wp\/v2\/dai_event_location?post=61664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}